{"id":10221,"date":"2023-02-21T15:23:42","date_gmt":"2023-02-21T15:23:42","guid":{"rendered":"https:\/\/rugbymajadahonda.com\/web\/?p=10221"},"modified":"2023-02-21T17:06:55","modified_gmt":"2023-02-21T17:06:55","slug":"cronica-sub14-vs-ing-industriales-sierra","status":"publish","type":"post","link":"https:\/\/rugbymajadahonda.com\/web\/cronica-sub14-vs-ing-industriales-sierra\/","title":{"rendered":"Cr\u00f3nica Sub14 vs Ing Industriales Sierra"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"500\" src=\"https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2023\/02\/rugby_majadahonda-cronica-sub14.jpg\" alt=\"\" class=\"wp-image-10222\" srcset=\"https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2023\/02\/rugby_majadahonda-cronica-sub14.jpg 900w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2023\/02\/rugby_majadahonda-cronica-sub14-300x167.jpg 300w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2023\/02\/rugby_majadahonda-cronica-sub14-150x83.jpg 150w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2023\/02\/rugby_majadahonda-cronica-sub14-768x427.jpg 768w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2023\/02\/rugby_majadahonda-cronica-sub14-600x333.jpg 600w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><figcaption class=\"wp-element-caption\"><em>Cr\u00f3nica por Staff Sub14<\/em><\/figcaption><\/figure>\n\n\n\n<p>Se presentaba el equipo Sub14 azul con 22 jugadores en El Cantizal para afrontar el examen que todos est\u00e1bamos esperando, ya que hasta ahora todos los partidos jugados hab\u00edan sido peque\u00f1os test sin mayor importancia.<\/p>\n\n\n\n<p>Tra\u00edamos los deberes hechos, un buen rodaje, buenos entrenamientos, alguna jugada preparada y mucha motivaci\u00f3n\u2026pero hab\u00eda que jugarlo y hasta que el \u00e1rbitro no pita el final, puede pasar cualquier cosa.<br>Los primeros minutos ya dejaban ver que tenemos nivel de Primera, ataques veloces, defensas muy intensas, recuperaciones de bal\u00f3n de uno y otro lado, por fin est\u00e1bamos compitiendo con equipos de nuestro nivel\u2026\u2026se tardaron 25 minutos en abrir el marcador y fueron los chicos de Industriales. En la zona de marca, esperando la transformaci\u00f3n, solo hab\u00eda un mensaje \u201csi me golpean, me levanto y golpeo\u201d\u2026.y as\u00ed lo hicimos, en dos minutos hab\u00edamos igualado el partido.<\/p>\n\n\n\n<p>La segunda parte, no fue muy distinta, el juego era de alto nivel. Juego al pie, contrataques, placajes, balones al exterior donde los alas corr\u00edan como locos\u2026.volvieron a ponerse por delante, pero nuestra consigna, volv\u00eda a hacer efecto y les respondimos con dos ensayos y una transformaci\u00f3n muy esquinada de las de enmarcar.<\/p>\n\n\n\n<p>Con un 14-19 nos enfrent\u00e1bamos al achuch\u00f3n final de Indus, no pod\u00edan perder este partido en casa y menos ante un reci\u00e9n ascendido, pero se encontraron con un equipo lleno de coraje y que no estaba dispuestos a perder ese partido\u2026..y as\u00ed, hasta la \u00faltima jugada donde bloqueamos su bal\u00f3n dentro de la zona de ensayo\u2026.y salimos del atolladero con un bote pronto desde la l\u00ednea de ensayo y el pitido final del partido.<\/p>\n\n\n\n<p>Este s\u00e1bado vimos que podemos jugar de tu a tu a los grandes equipos, vimos un equipo capaz de sobreponerse a las adversidades, vimos un equipo con mucha personalidad, con una gran capacidad de defender, avanzar, circular, ocupar espacio\u2026.todo eso que venimos escuchando desde septiembre se puso en pr\u00e1ctica. Y sobre todo vimos un magn\u00edfico grupo de 22 chavales con una enorme ilusi\u00f3n y ganas de jugar a esto llamado RUGBY que aunque a veces veamos actuaciones reprochables, no nos deben cambiar la idea de que este es un deporte distinto y la mayor\u00eda debemos cuidarlo, para no perder sus valores.<\/p>\n\n\n\n<p>Vamos \u201cpartido a partido\u201d que aun nos queda mucho camino por recorrer y el pr\u00f3ximo s\u00e1bado habr\u00e1 m\u00e1s.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-medium\"><img decoding=\"async\" width=\"300\" height=\"68\" src=\"https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/02\/LOGO-RUGBY-MAJADAHONDA-bicolor-300x68.png\" alt=\"\" class=\"wp-image-4335\" srcset=\"https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/02\/LOGO-RUGBY-MAJADAHONDA-bicolor-300x68.png 300w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/02\/LOGO-RUGBY-MAJADAHONDA-bicolor-1500x342.png 1500w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/02\/LOGO-RUGBY-MAJADAHONDA-bicolor-768x175.png 768w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/02\/LOGO-RUGBY-MAJADAHONDA-bicolor-1024x234.png 1024w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/02\/LOGO-RUGBY-MAJADAHONDA-bicolor-1536x350.png 1536w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/02\/LOGO-RUGBY-MAJADAHONDA-bicolor-600x137.png 600w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/02\/LOGO-RUGBY-MAJADAHONDA-bicolor.png 1911w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Se presentaba el equipo Sub14 azul con 22 jugadores en El Cantizal para afrontar el examen que todos est\u00e1bamos esperando, ya que hasta ahora todos los partidos jugados hab\u00edan sido peque\u00f1os test sin mayor importancia. Tra\u00edamos los deberes hechos, un buen rodaje, buenos entrenamientos, alguna jugada preparada y mucha motivaci\u00f3n\u2026pero hab\u00eda que jugarlo y hasta que el \u00e1rbitro no pita el final, puede pasar cualquier cosa.Los primeros minutos ya dejaban ver que tenemos nivel de Primera, ataques veloces, defensas muy intensas, recuperaciones de bal\u00f3n de uno y otro lado, por fin est\u00e1bamos compitiendo con equipos de nuestro nivel\u2026\u2026se tardaron 25&#8230; <\/p>\n","protected":false},"author":1,"featured_media":10222,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"yes","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1,5,37,21],"tags":[],"class_list":["post-10221","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-academia","category-cronica","category-s14","category-todas"],"jetpack_featured_media_url":"https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2023\/02\/rugby_majadahonda-cronica-sub14.jpg","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/posts\/10221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/comments?post=10221"}],"version-history":[{"count":2,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/posts\/10221\/revisions"}],"predecessor-version":[{"id":10224,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/posts\/10221\/revisions\/10224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/media\/10222"}],"wp:attachment":[{"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/media?parent=10221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/categories?post=10221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/tags?post=10221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}