{"id":2933,"date":"2020-02-06T10:00:14","date_gmt":"2020-02-06T10:00:14","guid":{"rendered":"http:\/\/rugbymajadahonda.com\/web\/?p=2933"},"modified":"2020-03-11T13:45:38","modified_gmt":"2020-03-11T13:45:38","slug":"rugby-majadahonda-amplia-convenio-con-la-uax","status":"publish","type":"post","link":"https:\/\/rugbymajadahonda.com\/web\/rugby-majadahonda-amplia-convenio-con-la-uax\/","title":{"rendered":"Rugby Majadahonda ampl\u00eda convenio con la UAX"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"500\" src=\"http:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2020\/02\/rugby-majadahonda-acuerdo-uax.jpg\" alt=\"\" class=\"wp-image-2934\" srcset=\"https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2020\/02\/rugby-majadahonda-acuerdo-uax.jpg 900w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2020\/02\/rugby-majadahonda-acuerdo-uax-600x333.jpg 600w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2020\/02\/rugby-majadahonda-acuerdo-uax-300x167.jpg 300w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2020\/02\/rugby-majadahonda-acuerdo-uax-768x427.jpg 768w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2020\/02\/rugby-majadahonda-acuerdo-uax-150x83.jpg 150w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Rugby Majadahonda ampl\u00eda convenio con la UAX<\/h2>\n\n\n\n<p class=\"has-text-align-justify\">En los \u00faltimos meses, el apoyo de la Universidad Alfonso X &#8211; El Sabio proporcionando las instalaciones de las cuales el Club no ha podido disponer en toda la temporada para ejercer la pr\u00e1ctica de sus actividades de manera habitual.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Una vez recuperadas las instalaciones del Valle del Arcipreste, aunque con una clara reducci\u00f3n de su tiempo de uso, el convenio que compart\u00edan el club deportivo majariego y la instituci\u00f3n acad\u00e9mica ha dado un paso m\u00e1s all\u00e1 de lo acordado en su inicio.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Con la renovaci\u00f3n del convenio, los estudiantes de la Universidad Alfonso X &#8211; El Sabio del Grado en Medicina y Grado en Fisioterapia, podr\u00e1n realizar sus practicas en las instalaciones del Club de Rugby Majadahonda, conociendo de primera mano el trabajo de campo con jugadores.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Un paso m\u00e1s que nos acerca al club que queremos ser.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rugby Majadahonda ampl\u00eda convenio con la UAX En los \u00faltimos meses, el apoyo de la Universidad Alfonso X &#8211; El Sabio proporcionando las instalaciones de las cuales el Club no ha podido disponer en toda la temporada para ejercer la pr\u00e1ctica de sus actividades de manera habitual. Una vez recuperadas las instalaciones del Valle del Arcipreste, aunque con una clara reducci\u00f3n de su tiempo de uso, el convenio que compart\u00edan el club deportivo majariego y la instituci\u00f3n acad\u00e9mica ha dado un paso m\u00e1s all\u00e1 de lo acordado en su inicio. Con la renovaci\u00f3n del convenio, los estudiantes de la Universidad&#8230; <\/p>\n","protected":false},"author":1,"featured_media":2934,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[26,10,21],"tags":[],"class_list":["post-2933","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-club","category-noticias","category-todas"],"jetpack_featured_media_url":"https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2020\/02\/rugby-majadahonda-acuerdo-uax.jpg","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/posts\/2933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/comments?post=2933"}],"version-history":[{"count":2,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/posts\/2933\/revisions"}],"predecessor-version":[{"id":3168,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/posts\/2933\/revisions\/3168"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/media\/2934"}],"wp:attachment":[{"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/media?parent=2933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/categories?post=2933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/tags?post=2933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}