{"id":5558,"date":"2021-06-21T10:32:34","date_gmt":"2021-06-21T10:32:34","guid":{"rendered":"http:\/\/rugbymajadahonda.com\/web\/?p=5558"},"modified":"2021-06-21T10:32:40","modified_gmt":"2021-06-21T10:32:40","slug":"rugby-majadahonda-da-el-primera-paso-en-las-gps-copa-de-la-reina-iberdrola","status":"publish","type":"post","link":"https:\/\/rugbymajadahonda.com\/web\/rugby-majadahonda-da-el-primera-paso-en-las-gps-copa-de-la-reina-iberdrola\/","title":{"rendered":"Rugby Majadahonda da el primera paso en las GPS Copa de la Reina Iberdrola"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"500\" src=\"http:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/rugby-majadahonda-gana-a-coruna-gps.jpg\" alt=\"\" class=\"wp-image-5559\" srcset=\"https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/rugby-majadahonda-gana-a-coruna-gps.jpg 900w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/rugby-majadahonda-gana-a-coruna-gps-300x167.jpg 300w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/rugby-majadahonda-gana-a-coruna-gps-768x427.jpg 768w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/rugby-majadahonda-gana-a-coruna-gps-600x333.jpg 600w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Rugby Majadahonda da el primera paso en las GPS Copa de la Reina Iberdrola<\/h2>\n\n\n\n<p class=\"has-text-align-justify\">Este fin de semana se disput\u00f3 en A Coru\u00f1a la primera de las series de las GPS Copa de la Reina Iberdrola de la modalidad ol\u00edmpica de rugby 7s. Rugby Majadahonda part\u00eda como cabeza de serie al ser el Campe\u00f3n en la edici\u00f3n 2018\/2019. En esta ocasi\u00f3n, volvi\u00f3 a cumplir como favorito y se hizo con la primera manga de la competici\u00f3n, que finalizar\u00e1 este fin de semana en Sant Cugat con el segundo y \u00faltimo torneo.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Las rhinas quedaban en cuadradas en el grupo A con todos los equipos debutantes: CR Sant Cugat, CR Turia y Eibar Rugby Taldea. A priori cruces que pod\u00edan parecer m\u00e1s asequibles por la falta de experiencia de los debutantes, pero que plantaron cara a las majariegas y demostraron por que hab\u00eda conseguido llegar ah\u00ed. Las Nacho del R\u00edo y Rodrigo Bernal lograron saldar todos sus partidos del primer d\u00eda con victorias, pasando como segundas en la general.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"304\" src=\"http:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/image-1024x304.png\" alt=\"\" class=\"wp-image-5560\" srcset=\"https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/image-1024x304.png 1024w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/image-300x89.png 300w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/image-768x228.png 768w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/image-600x178.png 600w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/image.png 1233w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-justify\">El d\u00eda dos consist\u00eda en una final tras otra para llegar a luchar por el primer puesto. El primer rival fueron las chicas de la Omega de Ol\u00edmpico de Pozuelo, contra quienes las rhinas hicieron un gran partido y lograron el pase claro a semifinales. Ah\u00ed se encontrar\u00edan al equipo encargado de hospedar la serie: CRAT Residencia Rialta. Un partido muy igualado que al final cay\u00f3 del lado azul y rojo en la \u00faltima jugada consiguiendo as\u00ed el pase a la final.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">La suerte quiso que la final fuera contras las colegiales de Complutense Cisneros, contra las que Rugby Majadahonda se tom\u00f3 la revancha de la final de Liga Iberdrola y se impuso con un claro 5 a 26.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"304\" src=\"http:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/image-2-1024x304.png\" alt=\"\" class=\"wp-image-5562\" srcset=\"https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/image-2-1024x304.png 1024w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/image-2-300x89.png 300w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/image-2-768x228.png 768w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/image-2-600x178.png 600w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/image-2.png 1223w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-justify\">De esta manera las rhinas son primeras en la general, lo que la dar\u00e1 cierta ventaja en los cruces del pr\u00f3ximo torneo, d\u00f3nde podr\u00edan volver a proclamarse campeonas por cuarto a\u00f1o consecutivo.<\/p>\n\n\n\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:35.87444%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/203981927_10159704350514574_7038450841432091863_n.jpg?strip=info&#038;w=600 600w,https:\/\/i2.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/203981927_10159704350514574_7038450841432091863_n.jpg?strip=info&#038;w=780 780w\" alt=\"\" data-height=\"1164\" data-id=\"5563\" data-link=\"http:\/\/rugbymajadahonda.com\/web\/?attachment_id=5563\" data-url=\"http:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/203981927_10159704350514574_7038450841432091863_n.jpg\" data-width=\"780\" src=\"https:\/\/i2.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/203981927_10159704350514574_7038450841432091863_n.jpg\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:64.12556%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i1.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/202988732_10159704353649574_6966988158771765439_n.jpg?strip=info&#038;w=600 600w,https:\/\/i1.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/202988732_10159704353649574_6966988158771765439_n.jpg?strip=info&#038;w=900 900w,https:\/\/i1.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/202988732_10159704353649574_6966988158771765439_n.jpg?strip=info&#038;w=1200 1200w,https:\/\/i1.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/202988732_10159704353649574_6966988158771765439_n.jpg?strip=info&#038;w=1371 1371w\" alt=\"\" data-height=\"1143\" data-id=\"5564\" data-link=\"http:\/\/rugbymajadahonda.com\/web\/?attachment_id=5564\" data-url=\"http:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/202988732_10159704353649574_6966988158771765439_n.jpg\" data-width=\"1371\" src=\"https:\/\/i1.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/202988732_10159704353649574_6966988158771765439_n.jpg\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:48.52630%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i1.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/202998090_10159704350804574_7538036710066400715_n.jpg?strip=info&#038;w=600 600w,https:\/\/i1.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/202998090_10159704350804574_7538036710066400715_n.jpg?strip=info&#038;w=732 732w\" alt=\"\" data-height=\"1144\" data-id=\"5565\" data-link=\"http:\/\/rugbymajadahonda.com\/web\/?attachment_id=5565\" data-url=\"http:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/202998090_10159704350804574_7538036710066400715_n.jpg\" data-width=\"732\" src=\"https:\/\/i1.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/202998090_10159704350804574_7538036710066400715_n.jpg\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:51.47370%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/203155944_10159704353594574_7076513986201497884_n.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/203155944_10159704353594574_7076513986201497884_n.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/203155944_10159704353594574_7076513986201497884_n.jpg?strip=info&#038;w=1200 1200w,https:\/\/i0.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/203155944_10159704353594574_7076513986201497884_n.jpg?strip=info&#038;w=1500 1500w,https:\/\/i0.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/203155944_10159704353594574_7076513986201497884_n.jpg?strip=info&#038;w=1763 1763w\" alt=\"\" data-height=\"1161\" data-id=\"5566\" data-link=\"http:\/\/rugbymajadahonda.com\/web\/?attachment_id=5566\" data-url=\"http:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/203155944_10159704353594574_7076513986201497884_n.jpg\" data-width=\"1763\" src=\"https:\/\/i0.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/203155944_10159704353594574_7076513986201497884_n.jpg\" data-amp-layout=\"responsive\"\/><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i1.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/203109294_10159704353464574_5263356292776409464_n.jpg?strip=info&#038;w=600 600w,https:\/\/i1.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/203109294_10159704353464574_5263356292776409464_n.jpg?strip=info&#038;w=900 900w,https:\/\/i1.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/203109294_10159704353464574_5263356292776409464_n.jpg?strip=info&#038;w=1200 1200w,https:\/\/i1.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/203109294_10159704353464574_5263356292776409464_n.jpg?strip=info&#038;w=1435 1435w\" alt=\"\" data-height=\"1155\" data-id=\"5567\" data-link=\"http:\/\/rugbymajadahonda.com\/web\/?attachment_id=5567\" data-url=\"http:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/203109294_10159704353464574_5263356292776409464_n.jpg\" data-width=\"1435\" src=\"https:\/\/i1.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/203109294_10159704353464574_5263356292776409464_n.jpg\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:35.75260%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i2.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/203872313_10159704353334574_5686390177460866588_n.jpg?strip=info&#038;w=600 600w,https:\/\/i2.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/203872313_10159704353334574_5686390177460866588_n.jpg?strip=info&#038;w=900 900w,https:\/\/i2.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/203872313_10159704353334574_5686390177460866588_n.jpg?strip=info&#038;w=1071 1071w\" alt=\"\" data-height=\"1161\" data-id=\"5569\" data-link=\"http:\/\/rugbymajadahonda.com\/web\/?attachment_id=5569\" data-url=\"http:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/203872313_10159704353334574_5686390177460866588_n.jpg\" data-width=\"1071\" src=\"https:\/\/i2.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/203872313_10159704353334574_5686390177460866588_n.jpg\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:64.24740%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i1.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/202728752_10159704350694574_7262694323707274062_n.jpg?strip=info&#038;w=600 600w,https:\/\/i1.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/202728752_10159704350694574_7262694323707274062_n.jpg?strip=info&#038;w=900 900w,https:\/\/i1.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/202728752_10159704350694574_7262694323707274062_n.jpg?strip=info&#038;w=1200 1200w,https:\/\/i1.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/202728752_10159704350694574_7262694323707274062_n.jpg?strip=info&#038;w=1500 1500w,https:\/\/i1.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/202728752_10159704350694574_7262694323707274062_n.jpg?strip=info&#038;w=1734 1734w\" alt=\"\" data-height=\"1044\" data-id=\"5568\" data-link=\"http:\/\/rugbymajadahonda.com\/web\/?attachment_id=5568\" data-url=\"http:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/202728752_10159704350694574_7262694323707274062_n.jpg\" data-width=\"1734\" src=\"https:\/\/i1.wp.com\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/202728752_10159704350694574_7262694323707274062_n.jpg\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><\/div><\/div>\n\n\n\n<p>Fotograf\u00edas de Diego Dolan &#8211; Rugby Femenino<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/02\/LOGO-RUGBY-MAJADAHONDA-bicolor-1024x234.png\" alt=\"\" class=\"wp-image-4335\" width=\"256\" height=\"59\" srcset=\"https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/02\/LOGO-RUGBY-MAJADAHONDA-bicolor-1024x234.png 1024w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/02\/LOGO-RUGBY-MAJADAHONDA-bicolor-1500x342.png 1500w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/02\/LOGO-RUGBY-MAJADAHONDA-bicolor-300x68.png 300w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/02\/LOGO-RUGBY-MAJADAHONDA-bicolor-768x175.png 768w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/02\/LOGO-RUGBY-MAJADAHONDA-bicolor-1536x350.png 1536w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/02\/LOGO-RUGBY-MAJADAHONDA-bicolor-600x137.png 600w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/02\/LOGO-RUGBY-MAJADAHONDA-bicolor.png 1911w\" sizes=\"(max-width: 256px) 100vw, 256px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Rugby Majadahonda da el primera paso en las GPS Copa de la Reina Iberdrola Este fin de semana se disput\u00f3 en A Coru\u00f1a la primera de las series de las GPS Copa de la Reina Iberdrola de la modalidad ol\u00edmpica de rugby 7s. Rugby Majadahonda part\u00eda como cabeza de serie al ser el Campe\u00f3n en la edici\u00f3n 2018\/2019. En esta ocasi\u00f3n, volvi\u00f3 a cumplir como favorito y se hizo con la primera manga de la competici\u00f3n, que finalizar\u00e1 este fin de semana en Sant Cugat con el segundo y \u00faltimo torneo. Las rhinas quedaban en cuadradas en el grupo A&#8230; <\/p>\n","protected":false},"author":1,"featured_media":5559,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5,29,10,19,21],"tags":[],"class_list":["post-5558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronica","category-gps-copa-de-la-reina","category-noticias","category-senior-femenino-noticias","category-todas"],"jetpack_featured_media_url":"https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/06\/rugby-majadahonda-gana-a-coruna-gps.jpg","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/posts\/5558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/comments?post=5558"}],"version-history":[{"count":1,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/posts\/5558\/revisions"}],"predecessor-version":[{"id":5570,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/posts\/5558\/revisions\/5570"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/media\/5559"}],"wp:attachment":[{"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/media?parent=5558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/categories?post=5558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/tags?post=5558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}