{"id":8748,"date":"2022-06-24T08:36:02","date_gmt":"2022-06-24T08:36:02","guid":{"rendered":"https:\/\/rugbymajadahonda.com\/web\/?p=8748"},"modified":"2022-08-28T21:35:53","modified_gmt":"2022-08-28T21:35:53","slug":"el-seven-nacional-se-cita-en-el-valle-del-arciprestre","status":"publish","type":"post","link":"https:\/\/rugbymajadahonda.com\/web\/el-seven-nacional-se-cita-en-el-valle-del-arciprestre\/","title":{"rendered":"El seven nacional se cita en el Valle del Arciprestre"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"500\" src=\"https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2022\/06\/rugby-majadahonda-seven-nacional-valle-arcipreste.jpg\" alt=\"\" class=\"wp-image-8752\" srcset=\"https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2022\/06\/rugby-majadahonda-seven-nacional-valle-arcipreste.jpg 900w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2022\/06\/rugby-majadahonda-seven-nacional-valle-arcipreste-300x167.jpg 300w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2022\/06\/rugby-majadahonda-seven-nacional-valle-arcipreste-768x427.jpg 768w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2022\/06\/rugby-majadahonda-seven-nacional-valle-arcipreste-600x333.jpg 600w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">El seven nacional se cita en el Valle del Arciprestre<\/h2>\n\n\n\n<p>El pr\u00f3ximo fin de semana el <strong>Valle del Arcipreste<\/strong>, el campo de Rugby de Majadahonda, acoger\u00e1 el torneo de la modalidad ol\u00edmpica de Rugby 7 masculino nacional, donde participar\u00e1n los 12 mejores equipos de Espa\u00f1a.&nbsp;<\/p>\n\n\n\n<p>A las 10:00 del s\u00e1bado empezar\u00e1 la competici\u00f3n con el arranque de los partidos de la fase de grupos y no parar\u00e1 hasta las 17:25 del domingo cuando se disputar\u00e1 la final.  <\/p>\n\n\n\n<p>El equipo vallisoletano del <strong>SilverStorm el Salvador<\/strong> defiende t\u00edtulo, pero \u00e9sta ha sido una larga temporada y est\u00e1 todo por decir en lo que al seven se refiere. <\/p>\n\n\n\n<p>Los equipos participantes est\u00e1n divididos en cuatro grupos con cuatro equipos por grupo: <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"732\" height=\"112\" src=\"https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2022\/06\/Captura-de-pantalla-2022-06-23-a-las-17.35.11.png\" alt=\"\" class=\"wp-image-8749\" srcset=\"https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2022\/06\/Captura-de-pantalla-2022-06-23-a-las-17.35.11.png 732w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2022\/06\/Captura-de-pantalla-2022-06-23-a-las-17.35.11-300x46.png 300w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2022\/06\/Captura-de-pantalla-2022-06-23-a-las-17.35.11-600x92.png 600w\" sizes=\"(max-width: 732px) 100vw, 732px\" \/><\/figure>\n<\/div>\n\n\n<p>Desde aqu\u00ed invitamos a todos aquellos que les apetezca, a acercarse al Valle y disfrutar de mucho rugby y por supuesto de unas cervezas en el bar que pondr\u00e1 el Club. <\/p>\n\n\n\n<p>Si quieres seguir en directo los resultados de la competici\u00f3n puedes hacerlo <strong><a href=\"https:\/\/ferugby.es\/calendario-campeonato-nacional-de-rugby-7\" target=\"_blank\" rel=\"noreferrer noopener\">pinchando aqu\u00ed<\/a><\/strong>.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-medium\"><img decoding=\"async\" width=\"300\" height=\"68\" src=\"https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/02\/LOGO-RUGBY-MAJADAHONDA-bicolor-300x68.png\" alt=\"\" class=\"wp-image-4335\" srcset=\"https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/02\/LOGO-RUGBY-MAJADAHONDA-bicolor-300x68.png 300w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/02\/LOGO-RUGBY-MAJADAHONDA-bicolor-1500x342.png 1500w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/02\/LOGO-RUGBY-MAJADAHONDA-bicolor-768x175.png 768w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/02\/LOGO-RUGBY-MAJADAHONDA-bicolor-1024x234.png 1024w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/02\/LOGO-RUGBY-MAJADAHONDA-bicolor-1536x350.png 1536w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/02\/LOGO-RUGBY-MAJADAHONDA-bicolor-600x137.png 600w, https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2021\/02\/LOGO-RUGBY-MAJADAHONDA-bicolor.png 1911w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>El seven nacional se cita en el Valle del Arciprestre El pr\u00f3ximo fin de semana el Valle del Arcipreste, el campo de Rugby de Majadahonda, acoger\u00e1 el torneo de la modalidad ol\u00edmpica de Rugby 7 masculino nacional, donde participar\u00e1n los 12 mejores equipos de Espa\u00f1a.&nbsp; A las 10:00 del s\u00e1bado empezar\u00e1 la competici\u00f3n con el arranque de los partidos de la fase de grupos y no parar\u00e1 hasta las 17:25 del domingo cuando se disputar\u00e1 la final. El equipo vallisoletano del SilverStorm el Salvador defiende t\u00edtulo, pero \u00e9sta ha sido una larga temporada y est\u00e1 todo por decir en lo&#8230; <\/p>\n","protected":false},"author":19,"featured_media":8752,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"yes","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10,21],"tags":[],"class_list":["post-8748","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-todas"],"jetpack_featured_media_url":"https:\/\/rugbymajadahonda.com\/web\/wp-content\/uploads\/2022\/06\/rugby-majadahonda-seven-nacional-valle-arcipreste.jpg","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/posts\/8748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/comments?post=8748"}],"version-history":[{"count":5,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/posts\/8748\/revisions"}],"predecessor-version":[{"id":9187,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/posts\/8748\/revisions\/9187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/media\/8752"}],"wp:attachment":[{"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/media?parent=8748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/categories?post=8748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rugbymajadahonda.com\/web\/wp-json\/wp\/v2\/tags?post=8748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}